{"id":2216,"date":"2026-03-25T14:25:00","date_gmt":"2026-03-25T14:25:00","guid":{"rendered":"https:\/\/opsb.com\/family-resources\/?post_type=resource&#038;p=2216"},"modified":"2026-04-17T18:15:22","modified_gmt":"2026-04-17T18:15:22","slug":"scoliosis-treatment-guide","status":"publish","type":"resource","link":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/","title":{"rendered":"Scoliosis Treatment Guide"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"848\" src=\"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/Screenshot-2026-04-17-121431.png\" alt=\"\" class=\"wp-image-2719\" srcset=\"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/Screenshot-2026-04-17-121431.png 648w, https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/Screenshot-2026-04-17-121431-229x300.png 229w, https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/Screenshot-2026-04-17-121431-147x193.png 147w, https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/Screenshot-2026-04-17-121431-539x705.png 539w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/figure>\n\n\n\n","protected":false},"featured_media":2217,"template":"","meta":{"_acf_changed":true,"_links_to":"","_links_to_target":""},"conditions":[14],"product":[36],"resource-type":[42],"class_list":["post-2216","resource","type-resource","status-publish","has-post-thumbnail","hentry","conditions-scoliosis","product-all","resource-type-print-guide"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scoliosis Treatment Guide - OPSB Family Resource Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scoliosis Treatment Guide - OPSB Family Resource Hub\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/\" \/>\n<meta property=\"og:site_name\" content=\"OPSB Family Resource Hub\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T18:15:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png\" \/>\n\t<meta property=\"og:image:width\" content=\"977\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/\",\"url\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/\",\"name\":\"Scoliosis Treatment Guide - OPSB Family Resource Hub\",\"isPartOf\":{\"@id\":\"https:\/\/opsb.com\/family-resources\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png\",\"datePublished\":\"2026-03-25T14:25:00+00:00\",\"dateModified\":\"2026-04-17T18:15:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#primaryimage\",\"url\":\"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png\",\"contentUrl\":\"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png\",\"width\":977,\"height\":549,\"caption\":\"Scoliosis Treatment Guide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/opsb.com\/family-resources\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scoliosis Treatment Guide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/opsb.com\/family-resources\/#website\",\"url\":\"https:\/\/opsb.com\/family-resources\/\",\"name\":\"OPSB Family Resource Hub\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/opsb.com\/family-resources\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scoliosis Treatment Guide - OPSB Family Resource Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/","og_locale":"en_US","og_type":"article","og_title":"Scoliosis Treatment Guide - OPSB Family Resource Hub","og_url":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/","og_site_name":"OPSB Family Resource Hub","article_modified_time":"2026-04-17T18:15:22+00:00","og_image":[{"width":977,"height":549,"url":"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/","url":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/","name":"Scoliosis Treatment Guide - OPSB Family Resource Hub","isPartOf":{"@id":"https:\/\/opsb.com\/family-resources\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#primaryimage"},"image":{"@id":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png","datePublished":"2026-03-25T14:25:00+00:00","dateModified":"2026-04-17T18:15:22+00:00","breadcrumb":{"@id":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#primaryimage","url":"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png","contentUrl":"https:\/\/opsb.com\/family-resources\/wp-content\/uploads\/sites\/2\/2026\/03\/ScreenShot-Tool-20260325102313.png","width":977,"height":549,"caption":"Scoliosis Treatment Guide"},{"@type":"BreadcrumbList","@id":"https:\/\/opsb.com\/family-resources\/resource\/scoliosis-treatment-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/opsb.com\/family-resources\/home\/"},{"@type":"ListItem","position":2,"name":"Scoliosis Treatment Guide"}]},{"@type":"WebSite","@id":"https:\/\/opsb.com\/family-resources\/#website","url":"https:\/\/opsb.com\/family-resources\/","name":"OPSB Family Resource Hub","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opsb.com\/family-resources\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/resource\/2216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/media\/2217"}],"wp:attachment":[{"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/media?parent=2216"}],"wp:term":[{"taxonomy":"conditions","embeddable":true,"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/conditions?post=2216"},{"taxonomy":"product","embeddable":true,"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/product?post=2216"},{"taxonomy":"resource-type","embeddable":true,"href":"https:\/\/opsb.com\/family-resources\/wp-json\/wp\/v2\/resource-type?post=2216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}